{"id":334,"date":"2016-12-15T10:39:13","date_gmt":"2016-09-14T10:33:13","guid":{"rendered":"http:\/\/poslovnipartneri.com\/?p=334"},"modified":"2016-12-28T12:40:28","modified_gmt":"2016-12-28T11:40:28","slug":"etra-d-o-o","status":"publish","type":"post","link":"https:\/\/poslovnipartneri.com\/en\/slovenia\/production-slovenia\/etra-d-o-o\/","title":{"rendered":"ETRA D.O.O."},"content":{"rendered":"<p>Production of equipment for industrial food processing.<\/p>\n<p>&nbsp;<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-1937 size-full\" src=\"http:\/\/poslovnipartneri.com\/en\/wp-content\/uploads\/sites\/2\/2016\/12\/eetra.jpg\" width=\"950\" height=\"1359\" srcset=\"https:\/\/poslovnipartneri.com\/en\/wp-content\/uploads\/sites\/2\/2016\/12\/eetra.jpg 950w, https:\/\/poslovnipartneri.com\/en\/wp-content\/uploads\/sites\/2\/2016\/12\/eetra-210x300.jpg 210w, https:\/\/poslovnipartneri.com\/en\/wp-content\/uploads\/sites\/2\/2016\/12\/eetra-768x1099.jpg 768w, https:\/\/poslovnipartneri.com\/en\/wp-content\/uploads\/sites\/2\/2016\/12\/eetra-716x1024.jpg 716w, https:\/\/poslovnipartneri.com\/en\/wp-content\/uploads\/sites\/2\/2016\/12\/eetra-102x146.jpg 102w, https:\/\/poslovnipartneri.com\/en\/wp-content\/uploads\/sites\/2\/2016\/12\/eetra-35x50.jpg 35w, https:\/\/poslovnipartneri.com\/en\/wp-content\/uploads\/sites\/2\/2016\/12\/eetra-52x75.jpg 52w\" sizes=\"auto, (max-width:767px) 480px, (max-width:950px) 100vw, 950px\" \/><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Production of equipment for industrial food processing. &nbsp;<\/p>\n","protected":false},"author":1,"featured_media":336,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[592,594],"tags":[898,877,878],"class_list":["post-334","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-production-slovenia","category-slovenia","tag-cnc-control","tag-electric-motors","tag-equipment-for-production-automation"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v25.2 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>ETRA D.O.O. - Business Partners<\/title>\n<meta name=\"description\" content=\"Production of equipment for industrial food processing\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/poslovnipartneri.com\/en\/slovenia\/production-slovenia\/etra-d-o-o\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"ETRA D.O.O. - Business Partners\" \/>\n<meta property=\"og:description\" content=\"Production of equipment for industrial food processing\" \/>\n<meta property=\"og:url\" content=\"https:\/\/poslovnipartneri.com\/en\/slovenia\/production-slovenia\/etra-d-o-o\/\" \/>\n<meta property=\"og:site_name\" content=\"Business Partners\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/projekat.poslovni.partneri\/\" \/>\n<meta property=\"article:published_time\" content=\"2016-09-14T10:33:13+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2016-12-28T11:40:28+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/poslovnipartneri.com\/en\/wp-content\/uploads\/sites\/2\/2016\/09\/logo_etra.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"893\" \/>\n\t<meta property=\"og:image:height\" content=\"595\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"admin\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"admin\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/poslovnipartneri.com\/en\/slovenia\/production-slovenia\/etra-d-o-o\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/poslovnipartneri.com\/en\/slovenia\/production-slovenia\/etra-d-o-o\/\"},\"author\":{\"name\":\"admin\",\"@id\":\"https:\/\/poslovnipartneri.com\/en\/#\/schema\/person\/4c0c7aac90ff4c012fa9c6b74550e174\"},\"headline\":\"ETRA D.O.O.\",\"datePublished\":\"2016-09-14T10:33:13+00:00\",\"dateModified\":\"2016-12-28T11:40:28+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/poslovnipartneri.com\/en\/slovenia\/production-slovenia\/etra-d-o-o\/\"},\"wordCount\":12,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/poslovnipartneri.com\/en\/#organization\"},\"image\":{\"@id\":\"https:\/\/poslovnipartneri.com\/en\/slovenia\/production-slovenia\/etra-d-o-o\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/poslovnipartneri.com\/en\/wp-content\/uploads\/sites\/2\/2016\/09\/logo_etra.jpg\",\"keywords\":[\"CNC control\",\"Electric motors\",\"Equipment for production automation\"],\"articleSection\":[\"Production\",\"Slovenia\"],\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/poslovnipartneri.com\/en\/slovenia\/production-slovenia\/etra-d-o-o\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/poslovnipartneri.com\/en\/slovenia\/production-slovenia\/etra-d-o-o\/\",\"url\":\"https:\/\/poslovnipartneri.com\/en\/slovenia\/production-slovenia\/etra-d-o-o\/\",\"name\":\"ETRA D.O.O. - Business Partners\",\"isPartOf\":{\"@id\":\"https:\/\/poslovnipartneri.com\/en\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/poslovnipartneri.com\/en\/slovenia\/production-slovenia\/etra-d-o-o\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/poslovnipartneri.com\/en\/slovenia\/production-slovenia\/etra-d-o-o\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/poslovnipartneri.com\/en\/wp-content\/uploads\/sites\/2\/2016\/09\/logo_etra.jpg\",\"datePublished\":\"2016-09-14T10:33:13+00:00\",\"dateModified\":\"2016-12-28T11:40:28+00:00\",\"description\":\"Production of equipment for industrial food processing\",\"breadcrumb\":{\"@id\":\"https:\/\/poslovnipartneri.com\/en\/slovenia\/production-slovenia\/etra-d-o-o\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/poslovnipartneri.com\/en\/slovenia\/production-slovenia\/etra-d-o-o\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/poslovnipartneri.com\/en\/slovenia\/production-slovenia\/etra-d-o-o\/#primaryimage\",\"url\":\"https:\/\/poslovnipartneri.com\/en\/wp-content\/uploads\/sites\/2\/2016\/09\/logo_etra.jpg\",\"contentUrl\":\"https:\/\/poslovnipartneri.com\/en\/wp-content\/uploads\/sites\/2\/2016\/09\/logo_etra.jpg\",\"width\":893,\"height\":595},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/poslovnipartneri.com\/en\/slovenia\/production-slovenia\/etra-d-o-o\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/poslovnipartneri.com\/en\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Slovenia\",\"item\":\"https:\/\/poslovnipartneri.com\/en\/slovenia\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Production\",\"item\":\"https:\/\/poslovnipartneri.com\/en\/slovenia\/production-slovenia\/\"},{\"@type\":\"ListItem\",\"position\":4,\"name\":\"ETRA D.O.O.\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/poslovnipartneri.com\/en\/#website\",\"url\":\"https:\/\/poslovnipartneri.com\/en\/\",\"name\":\"Business Partners\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\/\/poslovnipartneri.com\/en\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/poslovnipartneri.com\/en\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/poslovnipartneri.com\/en\/#organization\",\"name\":\"Inndex Media d.o.o.\",\"url\":\"https:\/\/poslovnipartneri.com\/en\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/poslovnipartneri.com\/en\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/poslovnipartneri.com\/en\/wp-content\/uploads\/sites\/2\/2016\/09\/inmedia-memo.png\",\"contentUrl\":\"https:\/\/poslovnipartneri.com\/en\/wp-content\/uploads\/sites\/2\/2016\/09\/inmedia-memo.png\",\"width\":300,\"height\":156,\"caption\":\"Inndex Media d.o.o.\"},\"image\":{\"@id\":\"https:\/\/poslovnipartneri.com\/en\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/projekat.poslovni.partneri\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\/\/poslovnipartneri.com\/en\/#\/schema\/person\/4c0c7aac90ff4c012fa9c6b74550e174\",\"name\":\"admin\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/poslovnipartneri.com\/en\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/4190d53ad95a6a13b3110fd13ea2cdd42ef616cf566c8b31f559f4de0d433c82?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/4190d53ad95a6a13b3110fd13ea2cdd42ef616cf566c8b31f559f4de0d433c82?s=96&d=mm&r=g\",\"caption\":\"admin\"},\"url\":\"https:\/\/poslovnipartneri.com\/en\/author\/admin\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"ETRA D.O.O. - Business Partners","description":"Production of equipment for industrial food processing","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/poslovnipartneri.com\/en\/slovenia\/production-slovenia\/etra-d-o-o\/","og_locale":"en_US","og_type":"article","og_title":"ETRA D.O.O. - Business Partners","og_description":"Production of equipment for industrial food processing","og_url":"https:\/\/poslovnipartneri.com\/en\/slovenia\/production-slovenia\/etra-d-o-o\/","og_site_name":"Business Partners","article_publisher":"https:\/\/www.facebook.com\/projekat.poslovni.partneri\/","article_published_time":"2016-09-14T10:33:13+00:00","article_modified_time":"2016-12-28T11:40:28+00:00","og_image":[{"width":893,"height":595,"url":"https:\/\/poslovnipartneri.com\/en\/wp-content\/uploads\/sites\/2\/2016\/09\/logo_etra.jpg","type":"image\/jpeg"}],"author":"admin","twitter_card":"summary_large_image","twitter_misc":{"Written by":"admin"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/poslovnipartneri.com\/en\/slovenia\/production-slovenia\/etra-d-o-o\/#article","isPartOf":{"@id":"https:\/\/poslovnipartneri.com\/en\/slovenia\/production-slovenia\/etra-d-o-o\/"},"author":{"name":"admin","@id":"https:\/\/poslovnipartneri.com\/en\/#\/schema\/person\/4c0c7aac90ff4c012fa9c6b74550e174"},"headline":"ETRA D.O.O.","datePublished":"2016-09-14T10:33:13+00:00","dateModified":"2016-12-28T11:40:28+00:00","mainEntityOfPage":{"@id":"https:\/\/poslovnipartneri.com\/en\/slovenia\/production-slovenia\/etra-d-o-o\/"},"wordCount":12,"commentCount":0,"publisher":{"@id":"https:\/\/poslovnipartneri.com\/en\/#organization"},"image":{"@id":"https:\/\/poslovnipartneri.com\/en\/slovenia\/production-slovenia\/etra-d-o-o\/#primaryimage"},"thumbnailUrl":"https:\/\/poslovnipartneri.com\/en\/wp-content\/uploads\/sites\/2\/2016\/09\/logo_etra.jpg","keywords":["CNC control","Electric motors","Equipment for production automation"],"articleSection":["Production","Slovenia"],"inLanguage":"en-US","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/poslovnipartneri.com\/en\/slovenia\/production-slovenia\/etra-d-o-o\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/poslovnipartneri.com\/en\/slovenia\/production-slovenia\/etra-d-o-o\/","url":"https:\/\/poslovnipartneri.com\/en\/slovenia\/production-slovenia\/etra-d-o-o\/","name":"ETRA D.O.O. - Business Partners","isPartOf":{"@id":"https:\/\/poslovnipartneri.com\/en\/#website"},"primaryImageOfPage":{"@id":"https:\/\/poslovnipartneri.com\/en\/slovenia\/production-slovenia\/etra-d-o-o\/#primaryimage"},"image":{"@id":"https:\/\/poslovnipartneri.com\/en\/slovenia\/production-slovenia\/etra-d-o-o\/#primaryimage"},"thumbnailUrl":"https:\/\/poslovnipartneri.com\/en\/wp-content\/uploads\/sites\/2\/2016\/09\/logo_etra.jpg","datePublished":"2016-09-14T10:33:13+00:00","dateModified":"2016-12-28T11:40:28+00:00","description":"Production of equipment for industrial food processing","breadcrumb":{"@id":"https:\/\/poslovnipartneri.com\/en\/slovenia\/production-slovenia\/etra-d-o-o\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/poslovnipartneri.com\/en\/slovenia\/production-slovenia\/etra-d-o-o\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/poslovnipartneri.com\/en\/slovenia\/production-slovenia\/etra-d-o-o\/#primaryimage","url":"https:\/\/poslovnipartneri.com\/en\/wp-content\/uploads\/sites\/2\/2016\/09\/logo_etra.jpg","contentUrl":"https:\/\/poslovnipartneri.com\/en\/wp-content\/uploads\/sites\/2\/2016\/09\/logo_etra.jpg","width":893,"height":595},{"@type":"BreadcrumbList","@id":"https:\/\/poslovnipartneri.com\/en\/slovenia\/production-slovenia\/etra-d-o-o\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/poslovnipartneri.com\/en\/"},{"@type":"ListItem","position":2,"name":"Slovenia","item":"https:\/\/poslovnipartneri.com\/en\/slovenia\/"},{"@type":"ListItem","position":3,"name":"Production","item":"https:\/\/poslovnipartneri.com\/en\/slovenia\/production-slovenia\/"},{"@type":"ListItem","position":4,"name":"ETRA D.O.O."}]},{"@type":"WebSite","@id":"https:\/\/poslovnipartneri.com\/en\/#website","url":"https:\/\/poslovnipartneri.com\/en\/","name":"Business Partners","description":"","publisher":{"@id":"https:\/\/poslovnipartneri.com\/en\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/poslovnipartneri.com\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/poslovnipartneri.com\/en\/#organization","name":"Inndex Media d.o.o.","url":"https:\/\/poslovnipartneri.com\/en\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/poslovnipartneri.com\/en\/#\/schema\/logo\/image\/","url":"https:\/\/poslovnipartneri.com\/en\/wp-content\/uploads\/sites\/2\/2016\/09\/inmedia-memo.png","contentUrl":"https:\/\/poslovnipartneri.com\/en\/wp-content\/uploads\/sites\/2\/2016\/09\/inmedia-memo.png","width":300,"height":156,"caption":"Inndex Media d.o.o."},"image":{"@id":"https:\/\/poslovnipartneri.com\/en\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/projekat.poslovni.partneri\/"]},{"@type":"Person","@id":"https:\/\/poslovnipartneri.com\/en\/#\/schema\/person\/4c0c7aac90ff4c012fa9c6b74550e174","name":"admin","image":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/poslovnipartneri.com\/en\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/4190d53ad95a6a13b3110fd13ea2cdd42ef616cf566c8b31f559f4de0d433c82?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/4190d53ad95a6a13b3110fd13ea2cdd42ef616cf566c8b31f559f4de0d433c82?s=96&d=mm&r=g","caption":"admin"},"url":"https:\/\/poslovnipartneri.com\/en\/author\/admin\/"}]}},"views":2115,"_links":{"self":[{"href":"https:\/\/poslovnipartneri.com\/en\/wp-json\/wp\/v2\/posts\/334","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/poslovnipartneri.com\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/poslovnipartneri.com\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/poslovnipartneri.com\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/poslovnipartneri.com\/en\/wp-json\/wp\/v2\/comments?post=334"}],"version-history":[{"count":0,"href":"https:\/\/poslovnipartneri.com\/en\/wp-json\/wp\/v2\/posts\/334\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/poslovnipartneri.com\/en\/wp-json\/wp\/v2\/media\/336"}],"wp:attachment":[{"href":"https:\/\/poslovnipartneri.com\/en\/wp-json\/wp\/v2\/media?parent=334"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/poslovnipartneri.com\/en\/wp-json\/wp\/v2\/categories?post=334"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/poslovnipartneri.com\/en\/wp-json\/wp\/v2\/tags?post=334"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}